{"id":2500,"date":"2026-03-28T12:53:54","date_gmt":"2026-03-28T11:53:54","guid":{"rendered":"https:\/\/v2.olym.nl\/track-record\/"},"modified":"2026-05-05T11:54:32","modified_gmt":"2026-05-05T09:54:32","slug":"track-record","status":"publish","type":"page","link":"https:\/\/www.olym.nl\/en\/track-record\/","title":{"rendered":"Track Record"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;2125&#8243; background_image_preload=&#8221;true&#8221; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;120px&#8221; bottom_padding=&#8221;120px&#8221; bottom_padding_phone=&#8221;80px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient=&#8221;linear-gradient(90deg, rgba(161,25,26,0.501) 0%, rgba(243,243,243,0) 33%)&#8221; advanced_gradient_angle=&#8221;90&#8243; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#FFFFFF&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;50px&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; gradient_type=&#8221;advanced&#8221; shape_type=&#8221;tilt_alt&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Track Record&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23FFFFFF&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;100px&#8221; left_padding_desktop=&#8221;100px&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;100px&#8221; top_padding_tablet=&#8221;80px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;80px&#8221; left_padding_tablet=&#8221;50px&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;50px&#8221; top_padding_phone=&#8221;50px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;50px&#8221; left_padding_phone=&#8221;0px&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column right_padding_desktop=&#8221;50px&#8221; right_padding_tablet=&#8221;0px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_wp_custommenu nav_menu=&#8221;43&#8243;][nectar_post_grid post_type=&#8221;post&#8221; blog_category=&#8221;all&#8221; blog_starting_category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;load-more&#8221; button_color=&#8221;black&#8221; columns=&#8221;1&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; grid_item_spacing=&#8221;10px&#8221; image_size=&#8221;large&#8221; aspect_ratio_image_size=&#8221;yes&#8221; custom_image_aspect_ratio=&#8221;default&#8221; content_next_to_image_image_width=&#8221;default&#8221; content_next_to_image_image_gap=&#8221;default&#8221; content_next_to_image_image_position=&#8221;left&#8221; image_loading=&#8221;default&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_stagger=&#8221;100&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;h2&#8243; heading_tag_render=&#8221;default&#8221; category_position=&#8221;default&#8221; display_excerpt=&#8221;yes&#8221; content_next_to_image_excerpt_pos=&#8221;default&#8221; excerpt_display=&#8221;default&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;before_post_meta&#8221; grid_style=&#8221;content_next_to_image&#8221; text_color=&#8221;dark&#8221; content_next_to_image_vertical_align=&#8221;middle&#8221; hover_effect=&#8221;none&#8221; border_radius=&#8221;10px&#8221; display_type=&#8221;grid&#8221; posts_per_page=&#8221;10&#8243; excerpt_length=&#8221;999&#8243; custom_font_size=&#8221;30px&#8221; font_size_phone=&#8221;24px&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;2125&#8243; background_image_preload=&#8221;true&#8221; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;120px&#8221; bottom_padding=&#8221;120px&#8221; bottom_padding_phone=&#8221;80px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient=&#8221;linear-gradient(90deg, rgba(161,25,26,0.501) 0%, rgba(243,243,243,0) 33%)&#8221; advanced_gradient_angle=&#8221;90&#8243; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#FFFFFF&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;50px&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; gradient_type=&#8221;advanced&#8221; shape_type=&#8221;tilt_alt&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Track Record&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23FFFFFF&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;100px&#8221; left_padding_desktop=&#8221;100px&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;100px&#8221; top_padding_tablet=&#8221;80px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;80px&#8221; left_padding_tablet=&#8221;50px&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;50px&#8221; top_padding_phone=&#8221;50px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;50px&#8221; left_padding_phone=&#8221;0px&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column right_padding_desktop=&#8221;50px&#8221; right_padding_tablet=&#8221;0px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_wp_custommenu nav_menu=&#8221;43&#8243;][nectar_post_grid post_type=&#8221;post&#8221; blog_category=&#8221;all&#8221; blog_starting_category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;load-more&#8221; button_color=&#8221;black&#8221; columns=&#8221;1&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; grid_item_spacing=&#8221;10px&#8221; image_size=&#8221;large&#8221; aspect_ratio_image_size=&#8221;yes&#8221; custom_image_aspect_ratio=&#8221;default&#8221; content_next_to_image_image_width=&#8221;default&#8221; content_next_to_image_image_gap=&#8221;default&#8221; content_next_to_image_image_position=&#8221;left&#8221; image_loading=&#8221;default&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_stagger=&#8221;100&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;h2&#8243; heading_tag_render=&#8221;default&#8221; category_position=&#8221;default&#8221; display_excerpt=&#8221;yes&#8221; content_next_to_image_excerpt_pos=&#8221;default&#8221; excerpt_display=&#8221;default&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;before_post_meta&#8221; grid_style=&#8221;content_next_to_image&#8221; text_color=&#8221;dark&#8221; content_next_to_image_vertical_align=&#8221;middle&#8221; hover_effect=&#8221;none&#8221; border_radius=&#8221;10px&#8221; display_type=&#8221;grid&#8221; posts_per_page=&#8221;10&#8243; excerpt_length=&#8221;999&#8243; custom_font_size=&#8221;30px&#8221; font_size_phone=&#8221;24px&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2500","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.olym.nl\/en\/wp-json\/wp\/v2\/pages\/2500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.olym.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.olym.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.olym.nl\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olym.nl\/en\/wp-json\/wp\/v2\/comments?post=2500"}],"version-history":[{"count":1,"href":"https:\/\/www.olym.nl\/en\/wp-json\/wp\/v2\/pages\/2500\/revisions"}],"predecessor-version":[{"id":2501,"href":"https:\/\/www.olym.nl\/en\/wp-json\/wp\/v2\/pages\/2500\/revisions\/2501"}],"wp:attachment":[{"href":"https:\/\/www.olym.nl\/en\/wp-json\/wp\/v2\/media?parent=2500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}